{"id":9499,"date":"2023-05-29T12:21:16","date_gmt":"2023-05-29T12:21:16","guid":{"rendered":"https:\/\/asisprojects.com\/?page_id=9499"},"modified":"2023-06-19T19:00:54","modified_gmt":"2023-06-19T17:00:54","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/asisprojects.com\/index.php\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de Cookies"},"content":{"rendered":"<section class=\"wpb-content-wrapper\">\n<h2>\u00bfQu\u00e9 son las cookies?<\/h2>\n\n<p>\n\tEn ingl\u00e9s, el t\u00e9rmino &quot;cookie&quot; significa galleta, pero en el \u00e1mbito de la navegaci\u00f3n web, una &quot;cookie&quot; es algo completamente distinto. Cuando accede a nuestro Sitio Web, en el navegador de su dispositivo se almacena una peque\u00f1a cantidad de texto que se denomina &quot;cookie&quot;. Este texto contiene informaci\u00f3n variada sobre su navegaci\u00f3n, h\u00e1bitos, preferencias, personalizaciones de contenidos, etc...\n<\/p>\n\n<p>\n\tExisten otras tecnolog\u00edas que funcionan de manera similar y que tambi\u00e9n se usan para recopilar datos sobre tu actividad de navegaci\u00f3n. Llamaremos &quot;cookies&quot; a todas estas tecnolog\u00edas en su conjunto.\n<\/p>\n\n<p>\n\tLos usos concretos que hacemos de estas tecnolog\u00edas se describen en el presente documento.\n<\/p>\n\n<h2>\u00bfPara qu\u00e9 se utilizan las cookies en esta web?<\/h2>\n\n<p>\n\tLas cookies son una parte esencial de c\u00f3mo funciona el Sitio Web. El objetivo principal de nuestras cookies es mejorar su experiencia en la navegaci\u00f3n. Por ejemplo, para recordar sus preferencias (idioma, pa\u00eds, etc.) durante la navegaci\u00f3n y en futuras visitas. La informaci\u00f3n recogida en las cookies nos permite adem\u00e1s mejorar la web, adaptarla a sus intereses como usuario, acelerar las b\u00fasquedas que realice, etc..\n<\/p>\n\n<p>\n\tEn determinados casos, si hemos obtenido su previo consentimiento informado, podremos utilizar cookies para otros usos, como por ejemplo para obtener informaci\u00f3n que nos permita mostrarle publicidad basada en el an\u00e1lisis de sus h\u00e1bitos de navegaci\u00f3n.\n<\/p>\n\n<h2>\u00bfPara qu\u00e9 NO se utilizan las cookies en esta web?<\/h2>\n\n<p>\n\tEn las cookies que utilizamos no se almacena informaci\u00f3n sensible de identificaci\u00f3n personal como su nombre, direcci\u00f3n, tu contrase\u00f1a, etc...\n<\/p>\n\n<h2>\u00bfQui\u00e9n utiliza la informaci\u00f3n almacenada en las cookies?<\/h2>\n\n<p>\n\tLa informaci\u00f3n almacenada en las cookies de nuestro Sitio Web es utilizada exclusivamente por nosotros, a excepci\u00f3n de aquellas identificadas m\u00e1s adelante como &quot;cookie de terceros&quot;, que son utilizadas y gestionadas por entidades externas que nos proporcionan servicios que mejoran la experiencia del usuario. Por ejemplo las estad\u00edsticas que se recogen sobre el n\u00famero de visitas, el contenido que m\u00e1s gusta, etc... lo suele gestionar Google Analytics.\n<\/p>\n\n\n\n<h2>\u00bfC\u00f3mo puede evitar el uso de cookies en este Sitio Web?<\/h2>\n\n<p>\n\tSi prefiere evitar el uso de las cookies, puede RECHAZAR su uso o puede CONFIGURAR las que quiere evitar y las que permite utilizar (en este documento le damos informaci\u00f3n ampliada al respecto de cada tipo de cookie, su finalidad, destinatario, temporalidad, etc... ).\n<\/p>\n\n<p>\n\tSi las ha aceptado, no volveremos a preguntarle a menos que borre las cookies en su dispositivo seg\u00fan se indica en el apartado siguiente. Si quiere revocar el consentimiento tendr\u00e1 que eliminar las cookies y volver a configurarlas.\n<\/p>\n\n\n<h2>\u00bfC\u00f3mo deshabilito y elimino la utilizaci\u00f3n de cookies?<\/h2>\n\n<p>\nEl Titular muestra informaci\u00f3n sobre su Pol\u00edtica de cookies en el banner de cookies accesible en todas las p\u00e1ginas del Sitio Web. El banner de cookies muestra informaci\u00f3n esencial sobre el tratamiento de datos y permite al Usuario realizar las siguientes acciones:\n<\/p>\n<p>\n<ul>\n  <li>ACEPTAR o RECHAZAR la instalaci\u00f3n de cookies, o retirar el consentimiento previamente otorgado.<\/li>\n  \n  \n  <li>Obtener informaci\u00f3n adicional en la p\u00e1gina de  <a href=https:\/\/asisprojects.com\/index.php\/politica-de-cookies\/>Pol\u00edtica de Cookies<\/a>.<\/li>\n<\/ul>\n<\/p>\n\n<p>\n\tPara restringir, bloquear o borrar las cookies de este Sitio Web (y las usada por terceros) puede hacerlo, en cualquier momento, modificando la configuraci\u00f3n de su navegador. Tenga en cuenta que esta configuraci\u00f3n es diferente en cada navegador.\n<\/p>\n\n<p> \n  En los siguientes enlaces encontrar\u00e1 instrucciones para habilitar o deshabilitar las cookies en los navegadores m\u00e1s comunes.\n<\/p>\n\n<p>\n  <ul>\n    <li><a rel=\"nofollow\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we\">Firefox<\/a><\/li>\n    <li><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=es\">Google Chrome<\/a><\/li>\n    <li><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href='https:\/\/support.microsoft.com\/es-es\/help\/17442\/windows-internet-explorer-delete-manage-cookies#ie=\"ie-10'>Internet Explorer<\/a><\/li>\n    <li><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href='https:\/\/support.microsoft.com\/es-es\/help\/4468242\/microsoft-edge-browsing-data-and-privacy'>Microsoft Edge<\/a><\/li>\n    <li><a rel=\"nofollow\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"http:\/\/support.apple.com\/kb\/HT1677?viewlocale=es_ES\">Safari<\/a><\/li>\n  <\/ul>\n<\/p>\n\n\n<h2>\u00bfQu\u00e9 tipos de cookies se utilizan en esta p\u00e1gina web?<\/h2>\n\n<p>\n\tCada p\u00e1gina web utiliza sus propias cookies. En nuestra web utilizamos las que se indican a continuaci\u00f3n:\n<\/p>\n\n<p>\n\t<b>SEG\u00daN LA ENTIDAD QUE LO GESTIONA<\/b>\n<\/p>\n\n<p>\n\t<b>Cookies propias:<\/b>\n<\/p>\n\n<p>\n\tSon aquellas que se env\u00edan al equipo terminal del Usuario desde un equipo o dominio gestionado por el propio editor y desde el que se presta el servicio solicitado por el Usuario.\n<\/p>\n\n<p>\n\t<b>Cookies de terceros:<\/b>\n<\/p>\n\n<p>\n\tSon aquellas que se env\u00edan al equipo terminal del Usuario desde un equipo o dominio que no es gestionado por el editor, sino por otra entidad que trata los datos obtenidos trav\u00e9s de las cookies.\n<\/p>\n\n<p>\n\tEn el caso de que las cookies sean servidas desde un equipo o dominio gestionado por el propio editor, pero la informaci\u00f3n que se recoja mediante estas sea gestionada por un tercero, no pueden ser consideradas como cookies propias si el tercero las utiliza para sus propias finalidades (por ejemplo, la mejora de los servicios que presta o la prestaci\u00f3n de servicios de car\u00e1cter publicitario a favor de otras entidades).\n<\/p>\n\n<p>\n\t<b>SEG\u00daN SU FINALIDAD<\/b>\n<\/p>\n\n<p>\n\t<b>Cookies t\u00e9cnicas:<\/b>\n<\/p>\n\n<p>\n\tSon aquellas necesarias para la navegaci\u00f3n y el buen funcionamiento de nuestro Sitio Web, como por ejemplo, controlar el tr\u00e1fico y la comunicaci\u00f3n de datos, identificar la sesi\u00f3n, acceder a partes de acceso restringido, realizar la solicitud de inscripci\u00f3n o participaci\u00f3n en un evento, contar visitas a efectos de la facturaci\u00f3n de licencias del software con el que funciona el servicio del Sitio Web, utilizar elementos de seguridad durante la navegaci\u00f3n, almacenar contenidos para la difusi\u00f3n de v\u00eddeos o sonido, habilitar contenidos din\u00e1micos (por ejemplo, animaci\u00f3n de carga de un texto o imagen) o compartir contenidos a trav\u00e9s de redes sociales.\n<\/p>\n\n<p>\n\t<b>Cookies de an\u00e1lisis:<\/b>\n<\/p>\n\n<p>\n\tPermiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del Sitio Web. \n<\/p>\n\n<p>\n\t<b>Cookies de preferencias o personalizaci\u00f3n:<\/b>\n<\/p>\n\n<p>\n\tSon aquellas que permiten recordar informaci\u00f3n para que el Usuario acceda al servicio con determinadas caracter\u00edsticas que pueden diferenciar su experiencia de la de otros usuarios, como, por ejemplo, el idioma, el n\u00famero de resultados a mostrar cuando el Usuario realiza una b\u00fasqueda, el aspecto o contenido del servicio en funci\u00f3n del tipo de navegador a trav\u00e9s del cual el Usuario accede al servicio o de la regi\u00f3n desde la que accede al servicio, etc.\n<\/p>\n\n\n\n<p>\n\t<b>SEG\u00daN EL PLAZO DE TIEMPO QUE PERMANECEN ACTIVADAS<\/b>\n<\/p>\n\n<p>\n\t<b>Cookies de sesi\u00f3n:<\/b>\n<\/p>\n\n<p>\n\tSon aquellas dise\u00f1adas para recabar y almacenar datos mientras el Usuario accede a una p\u00e1gina web.\n<\/p>\n\n<p>\n\tSe suelen emplear para almacenar informaci\u00f3n que solo interesa conservar para la prestaci\u00f3n del servicio solicitado por el Usuario en una sola ocasi\u00f3n (por ejemplo, una lista de productos adquiridos) y desaparecen al terminar la sesi\u00f3n.\n<\/p>\n\n<p>\n\t<b>Cookies persistentes:<\/b>\n<\/p>\n\n<p>\n\tSon aquellas en las que los datos siguen almacenados en el terminal y pueden ser accedidos y tratados durante un periodo definido por el responsable de la cookie, y que puede ir de unos minutos a varios a\u00f1os. A este respecto debe valorarse espec\u00edficamente si es necesaria la utilizaci\u00f3n de cookies persistentes, puesto que los riesgos para la privacidad podr\u00edan reducirse mediante la utilizaci\u00f3n de cookies de sesi\u00f3n. En todo caso, cuando se instalen cookies persistentes, se recomienda reducir al m\u00ednimo necesario su duraci\u00f3n temporal atendiendo a la finalidad de su uso. A estos efectos, el Dictamen 4\/2012 del GT29 indic\u00f3 que para que una cookie pueda estar exenta del deber de consentimiento informado, su caducidad debe estar relacionada con su finalidad. Debido a ello, es mucho m\u00e1s probable que se consideren como exceptuadas las cookies de sesi\u00f3n que las persistentes.\n<\/p>\n\n\n<p>\n\t<b>Detalle de cookies utilizadas en esta web:<\/b>\n<\/p>\n\n<p>[vc_row][vc_column][vc_column_text]<h1 class=\"wp-block-site-title\"><a href=\"https:\/\/asisprojects.com\" target=\"_self\" rel=\"home\">Asis Projects<\/a><\/h1><\/p>\r\n\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]\n\t\t<div id=\"wd-647499681e713\" class=\"title-wrapper wd-wpb set-mb-s reset-last-child  wd-rs-647499681e713 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h1 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Pol\u00edtica de Cookies<\/h1>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[\/vc_column][\/vc_row]<\/p><\/section>","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 son las cookies? En ingl\u00e9s, el t\u00e9rmino &quot;cookie&quot; significa galleta, pero en el \u00e1mbito de la navegaci\u00f3n web, una<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de Cookies - Asis Projects<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Cookies - Asis Projects\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 son las cookies? En ingl\u00e9s, el t\u00e9rmino &quot;cookie&quot; significa galleta, pero en el \u00e1mbito de la navegaci\u00f3n web, una\" \/>\n<meta property=\"og:url\" content=\"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Asis Projects\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-19T17:00:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/\",\"url\":\"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/\",\"name\":\"Pol\u00edtica de Cookies - Asis Projects\",\"isPartOf\":{\"@id\":\"https:\/\/asisprojects.com\/#website\"},\"datePublished\":\"2023-05-29T12:21:16+00:00\",\"dateModified\":\"2023-06-19T17:00:54+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/asisprojects.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/asisprojects.com\/#website\",\"url\":\"https:\/\/asisprojects.com\/\",\"name\":\"Asis Projects\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/asisprojects.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/asisprojects.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/asisprojects.com\/#organization\",\"name\":\"Asis Projects\",\"url\":\"https:\/\/asisprojects.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/asisprojects.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/asisprojects.com\/wp-content\/uploads\/2023\/05\/logotipo-1.png\",\"contentUrl\":\"https:\/\/asisprojects.com\/wp-content\/uploads\/2023\/05\/logotipo-1.png\",\"width\":609,\"height\":155,\"caption\":\"Asis Projects\"},\"image\":{\"@id\":\"https:\/\/asisprojects.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Cookies - Asis Projects","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de Cookies - Asis Projects","og_description":"\u00bfQu\u00e9 son las cookies? En ingl\u00e9s, el t\u00e9rmino &quot;cookie&quot; significa galleta, pero en el \u00e1mbito de la navegaci\u00f3n web, una","og_url":"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/","og_site_name":"Asis Projects","article_modified_time":"2023-06-19T17:00:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/","url":"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/","name":"Pol\u00edtica de Cookies - Asis Projects","isPartOf":{"@id":"https:\/\/asisprojects.com\/#website"},"datePublished":"2023-05-29T12:21:16+00:00","dateModified":"2023-06-19T17:00:54+00:00","breadcrumb":{"@id":"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/asisprojects.com\/index.php\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/asisprojects.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Cookies"}]},{"@type":"WebSite","@id":"https:\/\/asisprojects.com\/#website","url":"https:\/\/asisprojects.com\/","name":"Asis Projects","description":"","publisher":{"@id":"https:\/\/asisprojects.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asisprojects.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/asisprojects.com\/#organization","name":"Asis Projects","url":"https:\/\/asisprojects.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/asisprojects.com\/#\/schema\/logo\/image\/","url":"https:\/\/asisprojects.com\/wp-content\/uploads\/2023\/05\/logotipo-1.png","contentUrl":"https:\/\/asisprojects.com\/wp-content\/uploads\/2023\/05\/logotipo-1.png","width":609,"height":155,"caption":"Asis Projects"},"image":{"@id":"https:\/\/asisprojects.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/asisprojects.com\/index.php\/wp-json\/wp\/v2\/pages\/9499"}],"collection":[{"href":"https:\/\/asisprojects.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/asisprojects.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/asisprojects.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/asisprojects.com\/index.php\/wp-json\/wp\/v2\/comments?post=9499"}],"version-history":[{"count":3,"href":"https:\/\/asisprojects.com\/index.php\/wp-json\/wp\/v2\/pages\/9499\/revisions"}],"predecessor-version":[{"id":9504,"href":"https:\/\/asisprojects.com\/index.php\/wp-json\/wp\/v2\/pages\/9499\/revisions\/9504"}],"wp:attachment":[{"href":"https:\/\/asisprojects.com\/index.php\/wp-json\/wp\/v2\/media?parent=9499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}